{"text_format":"1","workbook":"xlsx","n_sheets":5,"sheets":["Calculation Sheet","Res EIA Tables","Cap Tables","TREL PLOT","TSD PLOT"],"not_rendered":{"charts":5,"images":2,"macros":1,"external_links":1,"defined_names":42,"comments":1,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Calculation Sheet","index":0,"n_rows":128,"n_cols":38,"rows_kept":128,"cut":false,"hidden":false,"merged":[[1,15,1,20],[101,1,101,4],[46,1,46,2],[112,1,112,2],[94,3,94,9],[106,1,106,4],[0,1,0,6],[84,1,84,3],[75,1,75,5],[91,1,91,5],[40,1,40,5],[25,1,25,2],[29,1,29,2],[33,1,33,3],[68,1,68,5],[70,1,70,3]]}
[null,"TPS25947xx Design Calculation Tool"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table - 1: Device Comparison Table"]
[null,null,"Constants Cells",null,null,null,null,null,null,null,null,null,null,null,null,"Part number","Overvoltage Response","Overcurrent response","AUXOFF or PG","FLT or PGTH","Response to Thermal Shutdown (TSD)",null,3.8,5.7,13.8]
[null,null,"Input/SelectCells",null,null,null,null,null,null,null,null,null,null,null,null,"TPS259470A","Adjustable OVLO","Active Current Limit","AUXOFF","FLT","Auto-Retry",null,"Short","Open",390]
[null,null,"Calculation Cells",null,null,null,null,null,null,null,null,null,null,null,null,"TPS259470L","Adjustable OVLO","Active Current Limit","AUXOFF","FLT","Latch-off"]
[null,null,"Calculated, but can be over-ridden by user",null,null,null,null,null,null,null,null,null,null,null,null,"TPS259472A","Pin Selectable OVC (3.8 V/5.7 V/13.8 V)","Active Current Limit","PG","PGTH","Auto-Retry"]
[null,null,"Error Cells, Must be Fixed",null,null,null,null,null,null,null,null,null,null,null,null,"TPS259472L","Pin Selectable OVC(3.8 V/5.7 V/13.8 V)","Active Current Limit","PG","PGTH","Latch-off"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"TPS259474A","Adjustable OVLO","Circuit Breaker","PG","PGTH","Auto-retry"]
[null,"Parameter","Description","Value "," Units","Tolerance","Recommended Value",null,null,null,null,null,null,null,null,"TPS259474L","Adjustable OVLO","Circuit Breaker","PG","PGTH","Latch-off"]
[null,"Select Device","Refer to Table-1 on top right side  and select based on OverVoltage Clamp/Lockout,Overcurrent response and Latch-off/Auto-retry requirement","TPS259470A"]
[null,"VIN (max)","Maximum Operating input voltage (magnitude)",12,"V"]
[null,"VIN (max)","Maximum Operating input voltage (magnitude)",16.8,"V"]
[null,"VCLAMP","Desired Over Voltage Clamp ",13.8,"V",3.5000000000000003E-2]
[null,"VIN (max) Selected","Maximum Operating input voltage selected from D6 and D7",{"$f":"IF(D10=P4,D12, IF(D10=P5,D12, IF(D10=P6,D11, IF(D10=P7,D11,IF(D10=P8,D12,D12)))))","v":16.8},"V"]
[null,"OVLO Set Point","Desired Over Voltage Lockout Set Point",18.5,"V",0.03]
[null,"UVLO Set Point","Desired Undervoltage Threshold (VIN Rising)",13.3,"V",0.03]
[null,"VUVP","Internal Undervoltage Protection Threshold (VIN Rising)",2.5299999999999998,"V",0.03]
[null,"Cout","Load Capacitance",2.2000000000000002,"uF",0.1]
[null,"Rlstart","Load at startup",1200,"Ohm",null,{"$f":"Vcc_max/Imax","v":7.6363636363636358}]
[null,"Load turn on voltage","Output voltage at which startup load will start drawing current",12,"V"]
[null,"Imax","Maximum continuous load current (magnitude)",2.2000000000000002,"A"]
[null,"Ilimit","Current Limit, 10.5% higher than maximum continuous load current",{"$f":"IF(1.105*Imax<0.5, 0.5, IF(1.105*Imax>6, 6,1.105*Imax ))","v":2.431},"A"]
[null,"tITIMER","Load transient blanking interval",5,"ms"]
[null,"TA, MAX","Maximum Operating Ambient temperature",65,"°C"]
[]
[null,"OVC set point calculations (TPS259472x)"]
[null,"VOVC","Over Voltage Clamp",{"$f":"D13","v":13.8},"V",3.5000000000000003E-2]
[null,"R_OVCSEL","Calculated value of Resistor at OVCSEL pin",{"$f":"INDEX(W4:Y4,MATCH(D27,W3:Y3))","v":390},"kOhm"]
[]
[null,"UVLO set point calculations (TPS259472x)"]
[null,"UVLO Set Point","Desired Undervoltage Threshold (VIN Rising)",{"$f":"D16","v":13.3},"V",0.03]
[null,"R1: Pullup at EN/UVLO Pin","Value > 350k recommended",470,"kOhm",0.01,null,null,null,null,{"$f":"D37","v":11.984210526315792},"Power Fail \n(VIN Falling)"]
[null,"R2_cal","Calculated value of Resistor at EN/UVLO pin",{"$f":"D32/(D31/OVref -1)","v":46.611570247933884},"kOhm",null,null,null,null,null,{"$f":"D36","v":13.073684210526316},"Release UVLO (VIN Rising)"]
[null,"SELECT THE VALUE OF RESISTORS AS CLOSEST AVAILABLE VALUE OF R2",null,null,null,null,null,null,null,null,{"$f":"D27","v":13.8},"OV Clamp\n(VIN Rising)"]
[null,"R2","Select the closest possible value as R2_cal",{"$f":"G35","v":47.5},"kOhm",{"$f":"F32","v":0.01},{"$f":"L56/L55*D33","v":47.5}]
[null,"UV_final_rising","Undervoltage Threshold (VIN Rising)",{"$f":"OVref*(1+D32/D35)","v":13.073684210526316},"V",{"$f":"SQRT(F126^2+F32^2+F35^2)","v":3.3166247903553998E-2}]
[null,"UV_final_falling","Undervoltage Threshold (VIN Falling)",{"$f":"UVref*(1+D32/D35)","v":11.984210526315792},"V",{"$f":"SQRT(F125^2+F32^2+F35^2)","v":6.4567793829431716E-2}]
[null,"I_R12","Current in R1, R2 Branch",{"$f":"D11*1000/(D32+D35)","v":23.188405797101449},"uA"]
[]
[]
[null,"UVLO, OVLO set point calculations (TPS259470x and TPS259474x)",null,null,null,null,null,null,null,null,null,"R2+R3"]
[null,"UVLO Set Point","Desired Undervoltage Threshold (VIN Rising)",{"$f":"D16","v":13.3},null,null,null,null,null,null,null,{"$f":"(OVref*D44)/(D42-OVref)","v":46.611570247933876}]
[null,"OVLO Set Point","Desired Over Voltage Lockout Set Point",{"$f":"D15","v":18.5},null,null,null,null,null,{"$f":"D51","v":12.030232558139534},"Power Fail (VIN Falling)","R2"]
[null,"R1: Pullup at EN/OVLO Pin"," Value > 350K recommended",470,"kOhm",0.01,null,null,null,{"$f":"D50","v":13.123890063424945},"Release UVLO (VIN Rising)",{"$f":"IF(D45>=10000,D45/100,IF(D45>=1000,D45/10,IF(D45>=100,D45,IF(D45>=10,D45*10,D45*100))))","v":131.01630556176005}]
[null,"R2_cal","Calculated value of Resistor at EN/OVLO pin",{"$f":"L42-D46","v":13.101630556176005},"kOhm",null,null,null,null,{"$f":"D53","v":16.736176470588234},"Release OVLO (VIN Falling)",{"$f":"INDEX('Res EIA Tables'!E$5:E$197,2+MATCH(L44,'Res EIA Tables'!E$5:E$197))","v":133}]
[null,"R3_cal","Calculated value of Resistor at EN/OVLO pin",{"$f":"(D44+L42)*OVref/D43","v":33.509939691757872},"kOhm",null,null,null,null,{"$f":"D52","v":18.257647058823526},"OV Cutoff (VIN Rising)","R3"]
[null,"SELECT THE VALUE OF RESISTORS AS CLOSEST AVAILABLE VALUE OF R2 & R3",null,null,null,null,null,null,null,null,null,{"$f":"IF(D46>=10000,D46/100,IF(D46>=1000,D46/10,IF(D46>=100,D46,IF(D46>=10,D46*10,D46*100))))","v":335.0993969175787}]
[null,"R2","Select the closest possible value as R2_cal",{"$f":"G48","v":13.299999999999999},"kOhm",0.01,{"$f":"L45*D45/L44","v":13.299999999999999},null,null,null,null,{"$f":"INDEX('Res EIA Tables'!E$5:E$197,2+MATCH(L47,'Res EIA Tables'!E$5:E$197))","v":340}]
[null,"R3","Select the closest possible value as R3_cal",{"$f":"G49","v":34},"kOhm",0.01,{"$f":"L48*D46/L47","v":34}]
[null,"UV_final_rising","Undervoltage Threshold (VIN Rising)",{"$f":"OVref*(D44+D48+D49)/(D48+D49)","v":13.123890063424945},"V",{"$f":"SQRT(F126^2+F44^2+F48^2+F49^2)","v":3.4641016151377546E-2},null,null,null,null,null,{"$f":"IF(D58>=100,D58,IF(D58>=10,D58*10,D58*100))","v":0}]
[null,"UV_final_falling","Undervoltage Threshold (VIN Falling)",{"$f":"UVref*(D44+D48+D49)/(D48+D49)","v":12.030232558139534},"V",{"$f":"SQRT(F125^2+F44^2+F48^2+F49^2)","v":6.5337584895678549E-2},null,null,null,null,null,{"$f":"IF(L50>1000,INDEX('Res EIA Tables'!E$5:E$197,MATCH(L50/10,'Res EIA Tables'!E$5:E$197))*10,INDEX('Res EIA Tables'!E$5:E$197,MATCH(L50,'Res EIA Tables'!E$5:E$197)))","v":{"$error":"#N/A"}}]
[null,"OV_final_rising","Overvoltage Threshold (VIN Rising)",{"$f":"OVref*(D44+D48+D49)/(D49)","v":18.257647058823526},"V",{"$f":"SQRT(F126^2+F44^2+F48^2+F49^2)","v":3.4641016151377546E-2}]
[null,"OV_final_falling","Overvoltage Threshold (VIN Falling)",{"$f":"UVref*(D44+D48+D49)/(D49)","v":16.736176470588234},"V",{"$f":"SQRT(F125^2+F44^2+F48^2+F49^2)","v":6.5337584895678549E-2},null,null,null,null,null,{"$f":"IF(D62>=10000,D62/100,IF(D62>=1000,D62/10,IF(D62>=100,D62,IF(D62>=10,D62*10,D62*100))))","v":552.94117647058818}]
[null,"I_R123","Current in R1, R2 and R3 Branch",{"$f":"D12*1000/(D44+D48+D49)","v":32.476319350473617},"uA",null,null,null,null,null,null,{"$f":"INDEX('Res EIA Tables'!E$5:E$197,2+MATCH(L53,'Res EIA Tables'!E$5:E$197))","v":562}]
[null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D33>=10000,D33/100,IF(D33>=1000,D33/10,IF(D33>=100,D33,IF(D33>=10,D33*10,D33*100))))","v":466.11570247933884}]
[null,null,null,null,null,null,null,null,null,null,null,{"$f":"INDEX('Res EIA Tables'!E$5:E$197,2+MATCH(L55,'Res EIA Tables'!E$5:E$197))","v":475}]
[null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D70>=10000,D70/100,IF(D70>=1000,D70/10,IF(D70>=100,D70,IF(D70>=10,D70*10,D70*100))))","v":137.14520773344302}]
[null,null,null,null,null,null,null,null,null,null,null,{"$f":"INDEX('Res EIA Tables'!E$5:E$197,2+MATCH(L57,'Res EIA Tables'!E$5:E$197))","v":140}]
[null,"PGset point calculations(TPS259472x and TPS259474x)"]
[null,"Desired PG threshold","Power good voltage threshold",11.4,"V",0.03]
[null,"R4: Pullup at PGTH pin","Select a value > 100k to keep I_R45 low",47,"kOhm",0.01]
[null,"R5_cal","Calculated value of Resistor at PGTH pin",{"$f":"D61*PGTH/(D60-PGTH)","v":5.5294117647058814},"kOhm"]
[null,"SELECT THE VALUE OF RESISTOR AS CLOSEST AVAILABLE VALUE OF R5"]
[null,"R5","Select the closest possible value as R5_cal",{"$f":"D62*L54/L53","v":5.62},"kOhm",0.01]
[null,"PG_final_rising","Power Good Threshold (Rising)",{"$f":"1.2*(D61+D64)/D64","v":11.235587188612097},"V",{"$f":"SQRT(F126^2+F61^2+F64^2)","v":3.3166247903553998E-2}]
[null,"PG_final_falling","Power Good Threshold (Falling)",{"$f":"1.1*(D61+D64)/D64","v":10.299288256227758},"V",{"$f":"SQRT(F125^2+F61^2+F64^2)","v":6.4567793829431716E-2}]
[null,"I_R45","Current in R4, R5 Branch",{"$f":"D12*1000/(D61+D64)","v":319.27023945267962},"uA"]
[]
[null,"Calculations for Ilimit (resistor on ILM Pin)",null,null,null,null,null,null,null,null,{"$f":"Icharge*(10^-3)","v":1.8333333333333335E-3},"Inrush Charging \nCurrent"]
[null,"RILM_Cal","Calculated current limit resistor",{"$f":"3334/(Ilimit)","v":1371.4520773344302},"Ohm",null,null,null,null,null,{"$f":"Ilimit_final","v":2.3814285714285712},"Overload Curr\nLimit"]
[null,"SELECT A ILIMIT RESISTOR WITH THE CLOSEST AVAILABLE VALUE OF Rilm_Cal"]
[null,"RILM","Select the closest available value of RLM_cal",{"$f":"G72","v":1400.0000000000002},"Ohm",0.01,{"$f":"L58/L57*D70","v":1400.0000000000002}]
[null,"Ilimit_final","Final current Limit Set Point",{"$f":"3334/D72","v":2.3814285714285712},"A",{"$f":"SQRT(0.105^2+F72^2)","v":0.10547511554864492}]
[null,"Isc","Scalable fast  trip threshold",{"$f":"2*Ilimit_final","v":4.7628571428571425},"A",{"$f":"F73","v":0.10547511554864492}]
[]
[null,"Calculations for SoftStart control (external cap on dVdt pin)"]
[null,"Parameter","Description","Value "," Units","Tolerance"]
[null,"I_dVdt","Internal charging current on dVdt",2.2000000000000002,"uA",0.104]
[null,"Icharge_fastest","Charging current when charging at fastest possible rate\nIf this current is < Ilimit, no capacitor is required at dVdT pin",{"$f":"Cout*(Vcc_max/D80)/1000","v":9.1891838135112841E-2},"A"]
[null,"Tchg_fastest","when no external capacitor  is connected (max. slew rate)",{"$f":"-0.0007*(Vcc_max^2) + 0.0301*Vcc_max + 0.0941","v":0.40221200000000007},"ms",0.15]
[null,"Tchg_req","The charging time required",20,"ms"]
[null,"Icharge_req","Charging (inrush) current desired in the system",1,"A"]
[null,"Cext_dvdt_cal1","calculated value of capacitor at dVdT pin for required Tcharge",{"$f":"IF(Tchg_req<D80,    0,  (2000*Tchg_req/Vcc_max))","v":2380.9523809523807},"pF"]
[null,"Cext_dvdt_cal2","calculated value of capacitor at dVdT pin for required Icharge",{"$f":"(2000*Cout/Icharge_req/1000)","v":4.4000000000000004},"pF"]
[null,"SELECT A CAPACITOR WITH THE CLOSEST POSSIBLE VALUE to max(Cext_dvdt_cal1, Cext_dvdt_cal2)",null,null,null,null,{"$f":"(MAX(D83,D84))/1000","v":2.3809523809523809},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Y95-AB93","v":0.19116799999999995}]
[null,"CdVdT_ext","The external capacitor connecetd across dVdT pin (OPEN, or >=1nF)",{"$f":"G87","v":2.4},"nf",0.1,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"D90+D93","v":2.3171428571428569E-2},{"$f":"AB93/I93","v":2.0533333333333334E-2},null,null,null,null,null,null,null,{"$f":"(23.97*Tchg_dvdt^(-0.33)*Tchg_dvdt)-AB93","v":179.0638347025278}]
[null,"Icharge","Charging Current as per dVdT setting",{"$f":"IF(Cdvdt_ext=\"OPEN\",D79*1000,(Cout*2000/Cdvdt_ext/1000))","v":1.8333333333333335},"mA",{"$f":"SQRT(F89^2+F18^2)","v":0.14142135623730953},{"$f":"IF(G85>1,INDEX('Cap Tables'!B4:B75,1+MATCH(G85,'Cap Tables'!B4:B75)),(INDEX('Cap Tables'!A4:A75,1+MATCH(G85*10,'Cap Tables'!A4:A75))/10))","v":2.4}]
[null,"Does Device Enter Current Limit during start-up?",null,{"$f":"((Icharge*(10^-3)+Vcc_max/Rlstart) >= Ilimit_final)","v":false},null,null,{"$f":"Cout*0.001*Rlstart*(Ilimit_final/Icharge -1+LN(Icharge/(Ilimit_final-Vcc_max/Rlstart)))","v":0.11429211386079224}]
[null,"Tchg_dvdt","charge time set",{"$f":"IF(D88, G88, IF(Cdvdt_ext=\"OPEN\",D80,Vcc_max*Cdvdt_ext*1000/2000))","v":20.16},"ms",{"$f":"F86","v":0.1}]
[null,"Pd_Cout_startup","Power dissipation due to load cap at start-up",{"$f":"0.5*Vcc_max*Icharge/10^3","v":1.5400000000000002E-2},"W",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"23.97*Tchg_dvdt^(-0.33)*Tchg_dvdt*0.8","v":143.47184216202226}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"37.14*Tchg_dvdt^(-0.31)*Tchg_dvdt*0.51","v":150.49100402332161}]
[null,"Total Power dissipation at Start-up",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"actual total energy for time tdvdt","time to tsd*power","actual energy for time vds>5.6"]
[null,"Pd_Rlstart","Power dissipation due to load resistance at start-up",{"$f":"(Vcc_max^2/Rlstart)*(1/6-(D20^2/2/Vcc_max^2)+(D20^3/3/Vcc_max^3))","v":7.7714285714285672E-3},"W",null,null,null,{"$f":"(Vcc_max-5.6)*Tchg_dvdt/Vcc_max","v":13.440000000000001},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"0.5*Vcc_max*Icharge/10^3*Tchg_dvdt","v":0.31046400000000007},{"$f":"13.312*Tchg_dvdt^(-0.4)*Tchg_dvdt*0.8","v":64.569528127274438},{"$f":"0.5*(Vcc_max+5.6)*Icharge/10^3*I93","v":0.27596800000000005},{"$f":"IF(D20<Vcc_max-5.6,AA95,AA93)","v":0.27596800000000005}]
[null,"Pd_startup","Total power dissipation at start-up",{"$f":"D90+D93","v":2.3171428571428569E-2},"W",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"(Vcc_max^2/Rlstart)*(1/6-(D20^2/2/Vcc_max^2)+(D20^3/3/Vcc_max^3))*Tchg_dvdt","v":0.15667199999999992},{"$f":"30.81*I93^(-0.31)*I93*0.8","v":148.03935380562069},{"$f":"(Tchg_dvdt/Rlstart)*(((Vcc_max-5.6)^2/2)-((Vcc_max-5.6)^3/3/Vcc_max)-(D20^2/2)+(D20^3/3/Vcc_max))","v":-4.8213333333333282E-2}]
[null,null,"                                                                                          Will the system have glitch-free startup?\n",{"$f":"IF(Vcc_max<=5.6,IF(D24<=25,AA98,IF(D24<=85,AA97,IF(D24<=125,AA99))),IF(D24<=25,AF96,IF(D24<=85,AA96,IF(D24<=125,AL96))))","v":"YES"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Y93+Y94","v":0.467136},null,{"$f":"AA93+AA94","v":0.22775466666666677}]
[null,"For CdVdt > 10 nF, it's recommended to add a 100-Ω resistor in series with the capacitor on the dVdt pin",null,{"$f":"IF(Vcc_max>=5.6,IF(D95=\"YES\",\"    We recommend verify startup on EVM for particular system test case\",\" \"),\" \")","v":"    We recommend verify startup on EVM for particular system test case"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(AB93<Z94,IF(Y95<Z90,\"YES\",\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\"),\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\")","v":"YES"},null,null,null,null,{"$f":"IF(AB93<Z94,IF(Y95<Z91,\"YES\",\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\"),\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\")","v":"YES"},null,null,null,null,null,{"$f":"IF(AB93<Z94,IF(Y95<Z93,\"YES\",\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\"),\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\")","v":"YES"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(Y95<Z90,\"YES\",\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\")","v":"YES"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"0.5*Vcc_max*Icharge/10^3","v":1.5400000000000002E-2},{"$f":"23.97*Tchg_dvdt^(-0.33)*0.8","v":7.1166588374018973},{"$f":"IF(Y95<Z91,\"YES\",\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\")","v":"YES"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"(Vcc_max^2/Rlstart)*(1/6-(D20^2/2/Vcc_max^2)+(D20^3/3/Vcc_max^3))","v":7.7714285714285672E-3},{"$f":"37.14*Tchg_dvdt^(-0.31)*0.51","v":7.4648315487758738},{"$f":"IF(Y95<Z93,\"YES\",\"NO, Increase Rlstart and/or Tchg_req; and/or Reduce Cout\")","v":"YES"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Y98+Y99","v":2.3171428571428569E-2},{"$f":"30.81*I93^(-0.31)*0.8","v":11.014832872442014}]
[]
[null,"Steady state Voltage drop & Power dissipation"]
[null,"Parameter","Description","Value "," Units","Tolerance"]
[null,"Vdrop","Maximum voltage drop across device @ 25 degC",{"$f":"Imax*Rdson_25deg","v":61.600000000000009},"mV"]
[null,"Pdiss_Imax","Steady state power dissipation with Max current @ 25degC ",{"$f":"Imax^2*Rdson_25deg","v":135.52000000000001},"mW"]
[]
[null,"Setting Overcurrent Blanking Interval (tITIMER)"]
[null,"Parameter","Description","Value "," Units","Tolerance"]
[null,"CITIMER_cal","Calculated Capacitor value at ITIMER pin",{"$f":"D23*1.8/1.5","v":6},"nF"]
[null,"CITIMER_sel","Select  Closest value as CITIMER_cal",{"$f":"G110","v":6.2},"nF",0.1,{"$f":"INDEX('Cap Tables'!B4:B75,1+MATCH(D109,'Cap Tables'!B4:B75))","v":6.2}]
[null,"tITIMER_final","Final Load transient blanking interval",{"$f":"D110*1.5/1.8","v":5.166666666666667},"ms"]
[]
[null,"Parameters internal to Device"]
[null,"Internal FET Parameters"]
[null,"Parameter","Description","Value "," Units","Tolerance"]
[null,"VIN(Max)","Maximum input voltage",23,"V"]
[null,"ID(max)","FET drain-source current rating (maximum)",5.5,"A"]
[null,"Rds(on)(typ)","FET Rds(on) for –40°C ≤ TJ ≤ 125°C ",28,"mOhm"]
[]
[null,"Thermal Parameters"]
[null,"Tj(max)","Deice maximum junction temperature",150,"C"]
[null,"RJA","Junction to ambient thermal resistance",41.7,"C/W"]
[]
[null,"Internal References"]
[null,"UVref","Internal Undervoltage reference (Falling)",1.1000000000000001,"V",6.3E-2]
[null,"OVref","Internal Overvoltage reference (Rising)",1.2,"V",0.03]
[null,"GainIMON","Current monitor gain",182,"uA/A",3.6999999999999998E-2]
[null,"PGTH","Internal Power good reference(Rising)",1.2,"v"]

{"sheet":"Res EIA Tables","index":1,"n_rows":197,"n_cols":7,"rows_kept":197,"cut":false,"hidden":false,"merged":[[12,2,19,2],[12,3,15,3],[12,4,13,4],[14,4,15,4],[16,3,19,3],[16,4,17,4],[18,4,19,4],[0,0,0,5],[4,0,35,0],[4,1,19,1],[4,2,11,2],[4,3,7,3],[4,4,5,4],[6,4,7,4],[8,3,11,3],[8,4,9,4],[10,4,11,4],[28,4,29,4],[30,4,31,4],[32,3,35,3],[32,4,33,4],[34,4,35,4],[36,0,67,0],[36,1,51,1],[36,2,43,2],[36,3,39,3],[36,4,37,4],[20,1,35,1],[20,2,27,2],[20,3,23,3],[20,4,21,4],[22,4,23,4],[24,3,27,3],[24,4,25,4],[26,4,27,4],[28,2,35,2],[28,3,31,3],[38,4,39,4],[40,3,43,3],[40,4,41,4],[42,4,43,4],[44,2,51,2],[44,3,47,3],[44,4,45,4],[46,4,47,4],[48,3,51,3],[48,4,49,4],[60,3,63,3],[60,4,61,4],[62,4,63,4],[64,3,67,3],[64,4,65,4],[66,4,67,4],[50,4,51,4],[52,1,67,1],[52,2,59,2],[52,3,55,3],[52,4,53,4],[54,4,55,4],[56,3,59,3],[56,4,57,4],[58,4,59,4],[60,2,67,2],[76,3,79,3],[76,4,77,4],[78,4,79,4],[80,3,83,3],[80,4,81,4],[82,4,83,4],[68,0,99,0],[68,1,83,1],[68,2,75,2],[68,3,71,3],[68,4,69,4],[70,4,71,4],[72,3,75,3],[72,4,73,4],[74,4,75,4],[76,2,83,2],[92,4,93,4],[94,4,95,4],[96,3,99,3],[96,4,97,4],[98,4,99,4],[100,0,131,0],[100,1,115,1],[100,2,107,2],[100,3,103,3],[100,4,101,4],[84,1,99,1],[84,2,91,2],[84,3,87,3],[84,4,85,4],[86,4,87,4],[88,3,91,3],[88,4,89,4],[90,4,91,4],[92,2,99,2],[92,3,95,3],[102,4,103,4],[104,3,107,3],[104,4,105,4],[106,4,107,4],[108,2,115,2],[108,3,111,3],[108,4,109,4],[110,4,111,4],[112,3,115,3],[112,4,113,4],[124,3,127,3],[124,4,125,4],[126,4,127,4],[128,3,131,3],[128,4,129,4],[130,4,131,4],[114,4,115,4],[116,1,131,1],[116,2,123,2],[116,3,119,3],[116,4,117,4],[118,4,119,4],[120,3,123,3],[120,4,121,4],[122,4,123,4],[124,2,131,2],[140,3,143,3],[140,4,141,4],[142,4,143,4],[144,3,147,3],[144,4,145,4],[146,4,147,4],[132,0,163,0],[132,1,147,1],[132,2,139,2],[132,3,135,3],[132,4,133,4],[134,4,135,4],[136,3,139,3],[136,4,137,4],[138,4,139,4],[140,2,147,2],[156,4,157,4],[158,4,159,4],[160,3,163,3],[160,4,161,4],[162,4,163,4],[164,0,195,0],[164,1,179,1],[164,2,171,2],[164,3,167,3],[164,4,165,4],[148,1,163,1],[148,2,155,2],[148,3,151,3],[148,4,149,4],[150,4,151,4],[152,3,155,3],[152,4,153,4],[154,4,155,4],[156,2,163,2],[156,3,159,3],[166,4,167,4],[168,3,171,3],[168,4,169,4],[170,4,171,4],[172,2,179,2],[172,3,175,3],[172,4,173,4],[174,4,175,4],[176,3,179,3],[176,4,177,4],[188,3,191,3],[188,4,189,4],[190,4,191,4],[192,3,195,3],[192,4,193,4],[194,4,195,4],[178,4,179,4],[180,1,195,1],[180,2,187,2],[180,3,183,3],[180,4,181,4],[182,4,183,4],[184,3,187,3],[184,4,185,4],[186,4,187,4],[188,2,195,2]]}
["Standard EIA Decade Resistor Values"]
[]
[0.2,0.1,0.05,0.02,0.01,"0.5%, 0.25%, 0.1%"]
["E6","E12","E24","E48","E96","E192"]
[100,100,100,100,100,100]
[null,null,null,null,null,101]
[null,null,null,null,102,102]
[null,null,null,null,null,104]
[null,null,null,105,105,105]
[null,null,null,null,null,106]
[null,null,null,null,107,107]
[null,null,null,null,null,109]
[null,null,110,110,110,110]
[null,null,null,null,null,111]
[null,null,null,null,113,113]
[null,null,null,null,null,114]
[null,null,null,115,115,115]
[null,null,null,null,null,117]
[null,null,null,null,118,118]
[null,null,null,null,null,120]
[null,120,120,121,121,121]
[null,null,null,null,null,123]
[null,null,null,null,124,124]
[null,null,null,null,null,126]
[null,null,null,127,127,127]
[null,null,null,null,null,129]
[null,null,null,null,130,130]
[null,null,null,null,null,132]
[null,null,130,133,133,133]
[null,null,null,null,null,135]
[null,null,null,null,137,137]
[null,null,null,null,null,138]
[null,null,null,140,140,140]
[null,null,null,null,null,142]
[null,null,null,null,143,143]
[null,null,null,null,null,145]
[150,150,150,147,147,147]
[null,null,null,null,null,149]
[null,null,null,null,150,150]
[null,null,null,null,null,152]
[null,null,null,154,154,154]
[null,null,null,null,null,156]
[null,null,null,null,158,158]
[null,null,null,null,null,160]
[null,null,160,162,162,162]
[null,null,null,null,null,164]
[null,null,null,null,165,165]
[null,null,null,null,null,167]
[null,null,null,169,169,169]
[null,null,null,null,null,172]
[null,null,null,null,174,174]
[null,null,null,null,null,176]
[null,180,180,178,178,178]
[null,null,null,null,null,180]
[null,null,null,null,182,182]
[null,null,null,null,null,184]
[null,null,null,187,187,187]
[null,null,null,null,null,189]
[null,null,null,null,191,191]
[null,null,null,null,null,193]
[null,null,200,196,196,196]
[null,null,null,null,null,198]
[null,null,null,null,200,200]
[null,null,null,null,null,203]
[null,null,null,205,205,205]
[null,null,null,null,null,208]
[null,null,null,null,210,210]
[null,null,null,null,null,213]
[220,220,220,215,215,215]
[null,null,null,null,null,218]
[null,null,null,null,221,221]
[null,null,null,null,null,223]
[null,null,null,226,226,226]
[null,null,null,null,null,229]
[null,null,null,null,232,232]
[null,null,null,null,null,234]
[null,null,240,237,237,237]
[null,null,null,null,null,240]
[null,null,null,null,243,243]
[null,null,null,null,null,246]
[null,null,null,249,249,249]
[null,null,null,null,null,252]
[null,null,null,null,255,255]
[null,null,null,null,null,258]
[null,270,270,261,261,261]
[null,null,null,null,null,264]
[null,null,null,null,267,267]
[null,null,null,null,null,271]
[null,null,null,274,274,274]
[null,null,null,null,null,277]
[null,null,null,null,280,280]
[null,null,null,null,null,284]
[null,null,300,287,287,287]
[null,null,null,null,null,291]
[null,null,null,null,294,294]
[null,null,null,null,null,298]
[null,null,null,301,301,301]
[null,null,null,null,null,305]
[null,null,null,null,309,309]
[null,null,null,null,null,312]
[330,330,330,316,316,316]
[null,null,null,null,null,320]
[null,null,null,null,324,324]
[null,null,null,null,null,328]
[null,null,null,332,332,332]
[null,null,null,null,null,336]
[null,null,null,null,340,340]
[null,null,null,null,null,344]
[null,null,360,348,348,348]
[null,null,null,null,null,352]
[null,null,null,null,357,357]
[null,null,null,null,null,361]
[null,null,null,365,365,365]
[null,null,null,null,null,370]
[null,null,null,null,374,374]
[null,null,null,null,null,379]
[null,390,390,383,383,383]
[null,null,null,null,null,388]
[null,null,null,null,392,392]
[null,null,null,null,null,397]
[null,null,null,402,402,402]
[null,null,null,null,null,407]
[null,null,null,null,412,412]
[null,null,null,null,null,417]
[null,null,430,422,422,422]
[null,null,null,null,null,427]
[null,null,null,null,432,432]
[null,null,null,null,null,437]
[null,null,null,442,442,442]
[null,null,null,null,null,448]
[null,null,null,null,453,453]
[null,null,null,null,null,459]
[470,470,470,464,464,464]
[null,null,null,null,null,470]
[null,null,null,null,475,475]
[null,null,null,null,null,481]
[null,null,null,487,487,487]
[null,null,null,null,null,493]
[null,null,null,null,499,499]
[null,null,null,null,null,505]
[null,null,510,511,511,511]
[null,null,null,null,null,517]
[null,null,null,null,523,523]
[null,null,null,null,null,530]
[null,null,null,536,536,536]
[null,null,null,null,null,542]
[null,null,null,null,549,549]
[null,null,null,null,null,556]
[null,560,560,562,562,562]
[null,null,null,null,null,569]
[null,null,null,null,576,576]
[null,null,null,null,null,583]
[null,null,null,590,590,590]
[null,null,null,null,null,597]
[null,null,null,null,604,604]
[null,null,null,null,null,612]
[null,null,620,619,619,619]
[null,null,null,null,null,626]
[null,null,null,null,634,634]
[null,null,null,null,null,642]
[null,null,null,649,649,649]
[null,null,null,null,null,657]
[null,null,null,null,665,665]
[null,null,null,null,null,673]
[680,680,680,681,681,681]
[null,null,null,null,null,690]
[null,null,null,null,698,698]
[null,null,null,null,null,706]
[null,null,null,715,715,715]
[null,null,null,null,null,723]
[null,null,null,null,732,732]
[null,null,null,null,null,741]
[null,null,750,750,750,750]
[null,null,null,null,null,759]
[null,null,null,null,768,768]
[null,null,null,null,null,777]
[null,null,null,787,787,787]
[null,null,null,null,null,796]
[null,null,null,null,806,806]
[null,null,null,null,null,816]
[null,820,820,825,825,825]
[null,null,null,null,null,835]
[null,null,null,null,845,845]
[null,null,null,null,null,856]
[null,null,null,866,866,866]
[null,null,null,null,null,876]
[null,null,null,null,887,887]
[null,null,null,null,null,898]
[null,null,910,909,909,909]
[null,null,null,null,null,920]
[null,null,null,null,931,931]
[null,null,null,null,null,942]
[null,null,null,953,953,953]
[null,null,null,null,null,965]
[null,null,null,null,976,976]
[null,null,null,null,null,988]
[1000,1000,1000,1000,1000,1000,"End Values Required for Processing"]

{"sheet":"Cap Tables","index":2,"n_rows":75,"n_cols":4,"rows_kept":75,"cut":false,"hidden":false,"merged":[]}
["Standard Capacitor Values"]
[]
["pF","nF","µF","mF"]
[1,1,1,1]
[1.1000000000000001,1.1000000000000001]
[1.2,1.2]
[1.3,1.3]
[1.5,1.5,1.5,1.5]
[1.6,1.6]
[1.8,1.8]
[2,2]
[2.2000000000000002,2.2000000000000002,2.2000000000000002,2.2000000000000002]
[2.4,2.4]
[2.7,2.7]
[3,3]
[3.3,3.3,3.3,3.3]
[3.6,3.6,{"$f":"C18","v":4.7}]
[3.9,3.9,{"$f":"C19","v":4.7}]
[4.3,4.3,{"$f":"C20","v":4.7}]
[4.7,4.7,4.7,4.7]
[5.0999999999999996,5.0999999999999996,{"$f":"C22","v":6.8}]
[5.6,5.6,{"$f":"C23","v":6.8}]
[6.2,6.2,{"$f":"C24","v":6.8}]
[6.8,6.8,6.8,6.8]
[7.5,7.5,{"$f":"C26","v":10}]
[8.1999999999999993,8.1999999999999993,{"$f":"C27","v":10}]
[9.1,9.1,{"$f":"C28","v":10}]
[10,10,10,10]
[11,{"$f":"B30","v":15},15]
[12,15,15]
[13,15,15]
[15,15,15]
[16,{"$f":"B34","v":22},22]
[18,22,22]
[20,22,22]
[22,22,22]
[24,{"$f":"B38","v":33},33]
[27,33,33]
[30,33,33]
[33,33,33]
[36,{"$f":"B42","v":47},47]
[39,47,47]
[43,47,47]
[47,47,47]
[51,{"$f":"B46","v":68},68]
[56,68,68]
[62,68,68]
[68,68,68]
[75,{"$f":"B50","v":100},100]
[82,100,100]
[91,100,100]
[100,100,100]
[110,{"$f":"B54","v":150},150]
[120,150,150]
[130,150,150]
[150,150,150]
[160,{"$f":"B58","v":220},220]
[180,220,220]
[200,220,220]
[220,220,220]
[240,{"$f":"B62","v":330},330]
[270,330,330]
[300,330,330]
[330,330,330]
[360,{"$f":"B66","v":470},470]
[390,470,470]
[430,470,470]
[470,470,470]
[510,{"$f":"B70","v":680},680]
[560,680,680]
[620,680,680]
[680,680,680]
[750,{"$f":"B74","v":1000},{"$f":"C74","v":1000}]
[820,{"$f":"B75","v":1000},{"$f":"C75","v":1000}]
[910,1000,1000]

{"sheet":"TREL PLOT","index":3,"n_rows":21,"n_cols":7,"rows_kept":21,"cut":false,"hidden":false,"merged":[]}
["Temperature(Degree C","VDS","IDS","Time(us)","TSD Time(in seconds)","TSD Time (in ms)","Power(W)"]
[25,5.3529999999999998,0.27399299999999999,null,16,{"$f":"E2*1000","v":16000},{"$f":"B2*C2","v":1.4666845289999999}]
[25,6.8410000000000002,0.27075900000000003,null,16,{"$f":"E3*1000","v":16000},{"$f":"B3*C3","v":1.8522623190000003}]
[25,8.9481760000000001,0.261876,13894435,13.894435,13894.434999999999,2.3433130000000002]
[25,11.915012000000001,0.26701200000000003,2313228,2.3132280000000001,2313.2280000000001,3.181451]
[25,14.348407999999999,0.27335700000000002,1179238,1.179238,1179.2380000000001,3.9222380000000001]
[25,17.190396,0.28403200000000001,658129,0.65812899999999996,658.12900000000002,4.8826229999999997]
[25,19.799713000000001,0.29450599999999999,420662,0.42066199999999998,420.66199999999998,5.8311339999999996]
[25,5.3110600000000003,1.316289,130330,0.13033,130.33000000000001,6.9908900000000003]
[25,6.8197210000000004,1.203395,30506,3.0505999999999998E-2,30.505999999999997,8.2068180000000002]
[25,7.324999,1.211452,19211,1.9210999999999999E-2,19.210999999999999,8.8738849999999996]
[25,8.7722549999999995,1.166436,6257,6.2570000000000004E-3,6.2570000000000006,10.232274]
[25,16.575237000000001,1.2151780000000001,915,9.1500000000000001E-4,0.91500000000000004,20.141863000000001]
[25,6.856617,4.7034180000000001,323,3.2299999999999999E-4,0.32300000000000001,32.249535999999999]
[25,9.1899270000000008,4.4264710000000003,209,2.0900000000000001E-4,0.20900000000000002,40.678944999999999]
[25,12.114768,4.2250550000000002,146,1.46E-4,0.14599999999999999,51.185561]
[25,14.038558,4.4889099999999997,122,1.22E-4,0.122,63.017823]
[25,15.945323,4.56142,105,1.05E-4,0.10500000000000001,72.733315000000005]
[25,17.325458000000001,4.6057309999999996,98,9.7999999999999997E-5,9.8000000000000004E-2,79.796398999999994]
[25,17.806688999999999,4.6369509999999998,95,9.5000000000000005E-5,9.5000000000000001E-2,82.568743999999995]
[25,19.580662,4.6802549999999998,87,8.7000000000000001E-5,8.6999999999999994E-2,91.642491000000007]

{"sheet":"TSD PLOT","index":4,"n_rows":63,"n_cols":26,"rows_kept":63,"cut":false,"hidden":false,"merged":[]}
[null,"VDS","IDS","Time(us)","Power(W)","TSD Time(in seconds)","TSD Time(in milliseconds)","Temperature(Degree C)",null,null,null,null,null,null,null,null,null,null,-40,null,25,null,85,null,125]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,4.5018440000000002,2031.0100000000002,2.1376979999999999,23021.011000000002,1.3278490000000001,20761.421999999999,1.0391170000000001,782.36500000000001]
[null,2.758,0.34,null,{"$f":"B3*C3","v":0.93772000000000011},null,null,25,null,null,null,null,null,null,null,null,null,null,4.8419489999999996,1365.979,2.1589710000000002,19870.804,1.345315,14738.652999999998,1.1385240000000001,583.23]
[null,2.771344,0.77135799999999999,23021011,2.1376979999999999,23.021011000000001,{"$f":"1000*F4","v":23021.011000000002},25,null,null,null,null,null,null,null,null,null,null,5.2583929999999999,936.73500000000001,2.2572540000000001,9809.0869999999995,1.3682460000000001,11355.892000000002,1.253053,441.81299999999999]
[null,2.8697349999999999,0.75232399999999999,19870804,2.1589710000000002,19.870804,19870.804,25,null,null,null,null,null,null,null,null,null,null,5.9441639999999998,673.94799999999998,2.3368220000000002,7830.7960000000003,2.1167229999999999,780.52,1.37079,344.15600000000001]
[null,3.197705,0.70589800000000003,9809087,2.2572540000000001,9.8090869999999999,9809.0869999999995,25,null,null,null,null,null,null,null,null,null,null,6.4502550000000003,505.13200000000001,4.5550519999999999,497.69499999999999,2.1513749999999998,750.42699999999991,4.087796,12.623000000000001]
[null,3.4016609999999998,0.68696500000000005,7830796,2.3368220000000002,7.8307960000000003,7830.7960000000003,25,null,null,null,null,null,null,null,null,null,null,14.795442,36.134,4.8378249999999996,375.97399999999999,2.597,405.90500000000003,4.6233829999999996,10.184000000000001]
[null,2.608384,1.7463120000000001,497695,4.5550519999999999,0.497695,{"$f":"1000*F8","v":497.69499999999999},25,null,null,null,null,null,null,null,null,null,null,18.052776999999999,28.509,5.3452330000000003,281.928,4.8429399999999996,73.719000000000008,5.023212,8.0069999999999997]
[null,3.2622740000000001,1.482961,375974,4.8378249999999996,0.37597399999999997,{"$f":"1000*F9","v":375.97399999999999},25,null,null,null,null,null,null,null,null,null,null,19.983069,22.233000000000001,5.8724150000000002,220.768,5.3878149999999998,56.152999999999999,5.5319539999999998,6.375]
[null,3.781901,1.4133720000000001,281928,5.3452330000000003,0.28192800000000001,281.928,25,null,null,null,null,null,null,null,null,null,null,22.382984,17.659000000000002,6.3085209999999998,169.96100000000001,5.8753190000000002,43.491,6.1079949999999998,5.1479999999999997]
[null,4.2953789999999996,1.3671469999999999,220768,5.8724150000000002,0.22076799999999999,220.768,25,null,null,null,null,null,null,null,null,null,null,null,null,17.054611000000001,14.929,6.403435,34.577999999999996,16.830774000000002,0.625]
[null,4.7996319999999999,1.314376,169961,6.3085209999999998,0.169961,169.96100000000001,25,null,null,null,null,null,null,null,null,null,null,null,null,18.871649000000001,11.42,16.844407,3.718,18.476970999999999,0.501]
[null,3.2059039999999999,5.3197510000000001,14929,17.054611000000001,1.4929E-2,14.929,25,null,null,null,null,null,null,null,null,null,null,null,null,20.611383,9.0839999999999996,18.913537000000002,2.879,21.184594000000001,0.40400000000000003]
[null,3.7296309999999999,5.0599239999999996,11420,18.871649000000001,1.142E-2,11.42,25,null,null,null,null,null,null,null,null,null,null,null,null,23.036021999999999,7.226,21.181204999999999,2.2850000000000001,23.563647,0.34900000000000003]
[null,4.2256850000000004,4.877643,9084,20.611383,9.0840000000000001E-3,9.0839999999999996,25,null,null,null,null,null,null,null,null,null,null,null,null,null,null,23.257106,1.6759999999999999]
[null,4.7453120000000002,4.8544799999999997,7226,23.036021999999999,7.2259999999999998E-3,7.226,25]
[null,null,null,null,null,null,0]
[null,3.4369999999999998,0.25950299999999998,null,{"$f":"B18*C18","v":0.89191181099999994},null,0,85]
[null,3.9350000000000001,0.24207899999999999,null,{"$f":"B19*C19","v":0.95258086499999994},null,0,85]
[null,4.45,0.2747,null,{"$f":"B20*C20","v":1.222415},null,0,85]
[null,4.7852829999999997,0.27748600000000001,20761422,1.3278490000000001,20.761422,20761.421999999999,85]
[null,4.8836740000000001,0.27547199999999999,14738653,1.345315,14.738652999999999,14738.652999999998,85]
[null,4.9851400000000003,0.27446500000000001,11355892,1.3682460000000001,11.355892000000001,11355.892000000002,85]
[null,2.561239,0.82644499999999999,780520,2.1167229999999999,0.78051999999999999,780.52,85]
[null,2.771344,0.77629300000000001,750427,2.1513749999999998,0.75042699999999996,750.42699999999991,85]
[null,3.9028399999999999,0.66541300000000003,405905,2.597,0.40590500000000002,405.90500000000003,85]
[null,3.2284519999999999,1.500081,73719,4.8429399999999996,7.3719000000000007E-2,73.719000000000008,85]
[null,3.7429549999999998,1.4394549999999999,56153,5.3878149999999998,5.6153000000000002E-2,56.152999999999999,85]
[null,4.2564320000000002,1.380339,43491,5.8753190000000002,4.3491000000000002E-2,43.491,85]
[null,4.7627350000000002,1.344487,34578,6.403435,3.4577999999999998E-2,34.577999999999996,85]
[null,3.1485089999999998,5.3499629999999998,3718,16.844407,3.718E-3,3.718,85]
[null,3.6671119999999999,5.1576110000000002,2879,18.913537000000002,2.879E-3,2.879,85]
[null,4.1744399999999997,5.0740230000000004,2285,21.181204999999999,2.2850000000000001E-3,2.2850000000000001,85]
[null,4.685867,4.9632449999999997,1676,23.257106,1.676E-3,1.6759999999999999,85]
[null,null,null,null,null,null,0]
[null,2.9578769999999999,0.35130499999999998,782365,1.0391170000000001,0.78236499999999998,782.36500000000001,125]
[null,3.461106,0.32894800000000002,583230,1.1385240000000001,0.58323000000000003,583.23,125]
[null,3.9684339999999998,0.31575500000000001,441813,1.253053,0.44181300000000001,441.81299999999999,125]
[null,4.4696119999999997,0.30669099999999999,344156,1.37079,0.34415600000000002,344.15600000000001,125]
[null,2.686277,1.521733,12623,4.087796,1.2623000000000001E-2,12.623000000000001,125]
[null,3.2182029999999999,1.4366350000000001,10184,4.6233829999999996,1.0184E-2,10.184000000000001,125]
[null,3.7347549999999998,1.344991,8007,5.023212,8.0070000000000002E-3,8.0069999999999997,125]
[null,4.2472079999999997,1.302492,6375,5.5319539999999998,6.3749999999999996E-3,6.375,125]
[null,4.7545359999999999,1.284667,5148,6.1079949999999998,5.1479999999999998E-3,5.1479999999999997,125]
[null,3.1341610000000002,5.3701049999999997,625,16.830774000000002,6.2500000000000001E-4,0.625,125]
[null,3.6589119999999999,5.0498539999999998,501,18.476970999999999,5.0100000000000003E-4,0.501,125]
[null,4.1693150000000001,5.081073,404,21.184594000000001,4.0400000000000001E-4,0.40400000000000003,125]
[null,4.6745939999999999,5.0407900000000003,349,23.563647,3.4900000000000003E-4,0.34900000000000003,125]
[null,null,null,null,null,null,0]
[null,2.9260000000000002,0.33941399999999999,null,{"$f":"B50*C50","v":0.99312536400000007},null,0,-40]
[null,3.43,0.30612899999999998,null,{"$f":"B51*C51","v":1.05002247},null,0,-40]
[null,3.931,0.28817700000000002,null,{"$f":"B52*C52","v":1.132823787},null,0,-40]
[null,4.4219999999999997,0.27689900000000001,null,{"$f":"B53*C53","v":1.224447378},null,0,-40]
[null,4.9359999999999999,0.26941999999999999,null,{"$f":"B54*C54","v":1.32985712},null,0,-40]
[null,2.7047249999999998,1.6644369999999999,2031010,4.5018440000000002,2.0310100000000002,2031.0100000000002,-40]
[null,3.2489499999999998,1.4903120000000001,1365979,4.8419489999999996,1.3659790000000001,1365.979,-40]
[null,3.7737020000000001,1.3934310000000001,936735,5.2583929999999999,0.93673499999999998,936.73500000000001,-40]
[null,4.2912790000000003,1.385173,673948,5.9441639999999998,0.67394799999999999,673.94799999999998,-40]
[null,4.8047560000000002,1.342473,505132,6.4502550000000003,0.50513200000000003,505.13200000000001,-40]
[null,3.1249370000000001,4.7346370000000002,36134,14.795442,3.6133999999999999E-2,36.134,-40]
[null,3.6558380000000001,4.9380680000000003,28509,18.052776999999999,2.8509E-2,28.509,-40]
[null,4.1744399999999997,4.7870059999999999,22233,19.983069,2.2232999999999999E-2,22.233000000000001,-40]
[null,4.6797180000000003,4.7829769999999998,17659,22.382984,1.7659000000000001E-2,17.659000000000002,-40]